{"id":3697,"date":"2017-11-14T17:20:40","date_gmt":"2017-11-14T15:20:40","guid":{"rendered":"https:\/\/teamdeck.io\/?p=3697"},"modified":"2022-05-24T14:35:33","modified_gmt":"2022-05-24T12:35:33","slug":"project-management-failures-save-projects-resource-allocation","status":"publish","type":"post","link":"https:\/\/teamdeck.io\/es\/gestion-de-proyectos\/los-fallos-en-la-gestion-de-proyectos-salvan-proyectos-asignacion-de-recursos\/","title":{"rendered":"Fracasos en la Gesti\u00f3n de Proyectos:  Salve sus proyectos del fracaso gracias a una asignaci\u00f3n eficiente de recursos"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Cualquiera que haya dirigido alguna vez un equipo o una empresa le dir\u00e1 que es extremadamente dif\u00edcil completar un proyecto sin planificar qui\u00e9n debe hacerlo y cu\u00e1ndo puede hacerse.  Sin embargo, muchas empresas recurren a <a href=\"https:\/\/teamdeck.io\/es\/gestion-de-proyectos\/asignacion-de-recursos-para-gestores-de-proyectos\/\">asignaci\u00f3n de recursos<\/a> y la actitud de \"esperemos que funcione\".<\/strong><\/p>\n<p><strong>Lo que consigue lectores gracias a este art\u00edculo:<\/strong><\/p>\n<ul>\n<li><strong>un conocimiento: <\/strong>62% de las organizaciones utilizan siempre o a menudo software de gesti\u00f3n de recursos para estimar y asignar recursos<\/li>\n<li><strong>sugerencias serias: <\/strong>pasos para evitar el fracaso del proyecto y el papel del software basado en la nube durante este proceso<\/li>\n<li><strong>entretenimiento<\/strong>: pantallas del planificador de recursos mezcladas con gifs de <a href=\"http:\/\/What gets readers of this article:   #a knowledge: 62% of organizations always or often use resource management software to estimate and allocate resource  #serious suggestions: steps on how to avoid project failure and the role of cloud-based software during this process #entertainment: screens of resource planner blended with gifs from https:\/\/giphy.com\/\" data-wplink-url-error=\"true\">giphy.com<\/a><\/li>\n<\/ul>\n<h2 style=\"text-align: center;\"><strong>El Project Management Institute resume una encuesta sobre el papel del software de gesti\u00f3n de recursos en los procesos de gesti\u00f3n de proyectos<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">De hecho, s\u00f3lo 62% de las organizaciones <\/span><span style=\"font-weight: 400;\">encuestados por el Project Management Institute<\/span><span style=\"font-weight: 400;\"> admitieron que siempre o a menudo utilizan la gesti\u00f3n de recursos para estimar y asignar sus recursos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es especialmente alarmante ya que <\/span><a href=\"https:\/\/www.pmi.org\/learning\/thought-leadership\/pulse\/pulse-of-the-profession-2017\"><span style=\"font-weight: 400;\">el mismo estudio<\/span><\/a><span style=\"font-weight: 400;\"> muestra que la asignaci\u00f3n insuficiente de recursos es lo que pone en peligro muchos proyectos. Cuando se les pregunt\u00f3 por las principales causas de los fracasos de sus proyectos anteriores, 23% de los encuestados mencionaron \"la previsi\u00f3n inadecuada de recursos\" y \"la dependencia de recursos\". <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Es cierto que no es el problema m\u00e1s com\u00fan, pero comparado con el \"cambio en las prioridades de la organizaci\u00f3n\" (mencionado por el 41% de los encuestados), la planificaci\u00f3n de recursos parece un factor que est\u00e1 muy en tus manos.<\/p>\n<p>Puede que la gesti\u00f3n de recursos no sea lo m\u00e1s importante para las empresas j\u00f3venes que, comprensiblemente, se centran en el crecimiento.<\/p>\n<p>Sin embargo, cuando se produce dicho crecimiento, tienen que mejorar r\u00e1pidamente su programaci\u00f3n para prosperar. Esto es especialmente cierto para las empresas que hacen malabarismos con varios proyectos al mismo tiempo: agencias, consultor\u00edas o empresas de software.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"3342\" height=\"1168\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14163727\/resource_allocation.png\" class=\"vc_single_image-img attachment-full\" alt=\"asignaci\u00f3n de recursos\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14163727\/resource_allocation.png 3342w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14163727\/resource_allocation-300x105.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14163727\/resource_allocation-768x268.png 768w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14163727\/resource_allocation-960x336.png 960w\" sizes=\"auto, (max-width: 3342px) 100vw, 3342px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><i><span style=\"font-weight: 400;\">Una asignaci\u00f3n inadecuada de recursos provoca el caos en la comunicaci\u00f3n y pone en peligro los proyectos.<\/span><\/i><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Soy un gran defensor de establecer procesos de gesti\u00f3n de recursos independientemente del tama\u00f1o de tu equipo. En realidad, una planificaci\u00f3n meditada del equipo puede acelerar tu crecimiento desde el principio y mantener una empresa saludable. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Veamos los pasos m\u00e1s importantes que hay que dar para disfrutar de las ventajas de la gesti\u00f3n de recursos.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\">Aumentar la visibilidad del equipo para alejar los proyectos exitosos de los fracasados<\/h2>\n<p><span style=\"font-weight: 400;\">Muchos equipos se enfrentan a una visibilidad limitada, lo que provoca una sobrecarga de trabajo de los empleados, retrasos en los proyectos o falta de comunicaci\u00f3n entre los distintos jefes de proyecto. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un calendario global de recursos es imprescindible para las empresas, independientemente de su tama\u00f1o. \u00bfEs usted la \u00fanica persona responsable de la asignaci\u00f3n de recursos en su empresa? (Como gestores de proyectos... conocemos la importancia de la gesti\u00f3n de la carga de trabajo).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una lista de empleados es un comienzo, pero recomiendo encarecidamente asignar atributos como el cargo, la antig\u00fcedad o la ubicaci\u00f3n (si trabaja en <a href=\"https:\/\/teamdeck.io\/es\/gestion-de-proyectos\/gestionar-proyectos-de-equipos-virtuales\/\">un equipo virtual<\/a>) para que pueda filtrar sus recursos f\u00e1cilmente. Los jefes de proyecto que a\u00fan no han trabajado con determinados miembros del equipo, no necesariamente conocen sus habilidades, por lo que este calendario de proyecto global con etiquetas personalizadas les ayuda a decidir a qui\u00e9n asignar para un proyecto determinado. <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"208\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14165442\/team_visibility.gif\" class=\"vc_single_image-img attachment-large\" alt=\"visibilidad del equipo\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Otra cosa que hay que tener en cuenta a la hora de mejorar la eficacia de la asignaci\u00f3n de recursos es la carga de trabajo. No es raro que las empresas dependan excesivamente de algunos empleados, mientras omiten a otros que podr\u00edan realizar una tarea determinada. Observando el calendario, puedes detectar a las personas con exceso de trabajo y a las infrautilizadas, y nivelar sus asignaciones.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"608\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14165631\/workload2-e1510671497562-960x608.png\" class=\"vc_single_image-img attachment-large\" alt=\"carga de trabajo del equipo\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14165631\/workload2-e1510671497562-960x608.png 960w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14165631\/workload2-e1510671497562-300x190.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14165631\/workload2-e1510671497562-768x487.png 768w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14165631\/workload2-e1510671497562.png 1458w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">La mayor visibilidad del equipo tambi\u00e9n ser\u00e1 apreciada por tus equipos de ventas y producto. A la hora de negociar nuevos acuerdos o decidir m\u00e1s funciones para tu app, podr\u00e1n tomar decisiones informadas sobre los plazos. \u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><strong>Aumentar la visibilidad del equipo para alejar los proyectos con \u00e9xito de los que fracasan<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Supongamos que tienes tres dise\u00f1adores en plantilla que no tienen encargos inmediatos y, por tanto, podr\u00edan trabajar en un proyecto reci\u00e9n ganado. Si tenemos en cuenta s\u00f3lo el calendario de trabajo, no hay ning\u00fan problema o incluso no hay muchas opciones. Pero resulta que uno de esos dise\u00f1adores est\u00e1 de baja por enfermedad, otro de vacaciones y el tercero acaba de pedir trabajar a tiempo parcial este mes. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Y as\u00ed de f\u00e1cil, tu proyecto corre peligro y puede que tengas que retrasarlo o subcontratar dise\u00f1adores adicionales. Ambas opciones suelen afectar a tu cuenta de resultados. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conocer la disponibilidad de su equipo es esencial para asignar los recursos con \u00e9xito. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tanto si su empleado se toma una baja prolongada como si s\u00f3lo se trata de una ausencia de medio d\u00eda, usted y sus jefes de proyecto deben saber qui\u00e9n puede asumir nuevas tareas de forma realista. \u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lo ideal es que muestre tanto las asignaciones de su equipo como los datos de disponibilidad en un mismo horario, para que pueda tener ambos en cuenta a la hora de planificar sus proyectos. Pide a tus empleados a tiempo parcial y a los aut\u00f3nomos con los que trabajas a menudo que compartan contigo su disponibilidad diaria. <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"919\" height=\"502\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170301\/team_availability.png\" class=\"vc_single_image-img attachment-large\" alt=\"disponibilidad del equipo\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170301\/team_availability.png 919w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170301\/team_availability-300x164.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170301\/team_availability-768x420.png 768w\" sizes=\"auto, (max-width: 919px) 100vw, 919px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">El funcionamiento de teamdeck consiste en que los propios empleados pueden introducir su disponibilidad e incluso solicitar d\u00edas libres. Los gestores aceptan o rechazan sus solicitudes y el horario se actualiza inmediatamente. <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"494\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/09\/25114154\/teamdeck-employee-vacation-960x494.png\" class=\"vc_single_image-img attachment-large\" alt=\"vacaciones de los empleados de teamdeck\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/09\/25114154\/teamdeck-employee-vacation-960x494.png 960w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/09\/25114154\/teamdeck-employee-vacation-300x154.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/09\/25114154\/teamdeck-employee-vacation-768x395.png 768w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/09\/25114154\/teamdeck-employee-vacation.png 1257w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><strong>Utiliza los datos que recoges<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Hay que reconocer que la previsi\u00f3n y la asignaci\u00f3n de recursos son en parte ciencia y en parte experiencia. Para aprovechar al m\u00e1ximo la parte cient\u00edfica de esta f\u00f3rmula, hay que empezar a utilizar datos hist\u00f3ricos: es obvio, pero nunca es sencillo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para muchas empresas, el control del tiempo es algo que han acordado con sus clientes. Otras piensan que es una reliquia corporativa que no encaja con la cultura relajada que est\u00e1n construyendo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mi postura sobre el control del tiempo es que, cuando se hace correctamente, no es intrusivo para los empleados y es esclarecedor para los directivos. Recomiendo hacer el seguimiento del trabajo en tiempo real o, al menos, rellenar las hojas de horas el mismo d\u00eda. Aumenta la precisi\u00f3n de los datos. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando asigne recursos a un nuevo proyecto, analice el tiempo empleado por los miembros de su equipo en sus tareas anteriores. Si superan repetidamente el <a href=\"https:\/\/teamdeck.io\/es\/gestion-de-proyectos\/como-estimar-proyectos\/\">tiempo estimado<\/a>pero pueden ser inadecuados para un proyecto con plazos ajustados. <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"358\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170655\/teamdeck_reports_accuracy-960x358.png\" class=\"vc_single_image-img attachment-large\" alt=\"informe de reservas y horarios\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170655\/teamdeck_reports_accuracy-960x358.png 960w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170655\/teamdeck_reports_accuracy-300x112.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170655\/teamdeck_reports_accuracy-768x286.png 768w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170655\/teamdeck_reports_accuracy.png 1255w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Tambi\u00e9n puede evaluar la utilizaci\u00f3n de su equipo (comparando las reservas de las personas con sus hojas de horas) y ver qu\u00e9 empleados han sido sobreutilizados en los \u00faltimos proyectos. Tal vez sea necesario contratar a una nueva persona con un conjunto de habilidades similar. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"385\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170853\/teamdeck_reports_utilization-960x385.png\" class=\"vc_single_image-img attachment-large\" alt=\"informes de utilizaci\u00f3n\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170853\/teamdeck_reports_utilization-960x385.png 960w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170853\/teamdeck_reports_utilization-300x120.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170853\/teamdeck_reports_utilization-768x308.png 768w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14170853\/teamdeck_reports_utilization.png 1232w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Adaptarse a los cambios<\/h2>\n<p><span style=\"font-weight: 400;\">Es posible que haya marcado todas las casillas y calculado los mejores calendarios para su equipo.  Pero es inevitable que algo cambie y afecte a tus planes: puede ser el alcance de tu proyecto o su calendario. La gente puede caer enferma o dejar la empresa a mitad del proyecto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es fundamental estar preparado para el cambio y ser capaz de actuar con rapidez cuando nos enfrentamos a \u00e9l. Algo que ayuda a mi empresa a gestionar varios proyectos diferentes a la vez es nuestro calendario en tiempo real. Todos los jefes de proyecto pueden ver la disponibilidad y la carga de trabajo de cada uno. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hay un problema con las hojas de c\u00e1lculo y los documentos que preparas meticulosamente antes del inicio del proyecto. Quedan obsoletos en cuanto algo cambia. En la mayor\u00eda de los proyectos, es muy pronto. No se puede controlar todo, as\u00ed que mejor prepararse para aceptar el cambio. <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_row-fluid redl-row-section feature-row vc_custom_1574416816256 vc_row-o-equal-height vc_row-o-content-middle vc_row-flex padding-medium bgv-default bgh-default halign-center\"><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section vc_row-o-content-middle vc_row-flex padding-default bgv-default bgh-default halign-default\"><\/div><div class=\"wpb_column vc_column_container text-center vc_col-sm-12 padding-default bgv-default bgh-default halign-center\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 class=\"ql-align-center\" style=\"text-align: center;\"><strong>Menos fracasos en la gesti\u00f3n de proyectos con <a href=\"https:\/\/teamdeck.io\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">software de planificaci\u00f3n de recursos de proyectos<\/a><\/strong><\/h2>\n<h3 class=\"ql-align-center\" style=\"text-align: center;\"><strong>Asignaci\u00f3n eficiente de recursos a sus empleados en m\u00faltiples proyectos: conozca por qu\u00e9 nuestro software de planificaci\u00f3n de recursos es elegido por empresas creativas y de TI de EE.UU., Asia y Reino Unido.<\/strong><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<a class=\"redl-btn   vc_custom_1596025898618 redl-btn-medium redl-btn-6a57d7d00d03a btn-icon-left redl-btn redl-btn-two vc_custom_1551260371526 redl-btn-medium redl-btn-5f2168a4adf5d btn-hover-one btn-icon-right signup-top\" href=\"https:\/\/app.teamdeck.io\/register\">30 d\u00edas de prueba GRATIS<\/a><div class=\"vc_empty_space\"   style=\"height: 32px\" ><span class=\"vc_empty_space_inner\"><\/span><\/div>\n<\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><\/div><\/div><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>","protected":false},"excerpt":{"rendered":"Una asignaci\u00f3n eficaz de los recursos le ayudar\u00e1 a entregar los proyectos a tiempo, mantener un equipo sano y asegurarse de que el trabajo de su equipo est\u00e1 correctamente planificado.","protected":false},"author":4,"featured_media":8730,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-3697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-project-management"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.8 (Yoast SEO v24.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Project Management Failures: Save Your Projects from Failure Thanks to...<\/title>\n<meta name=\"description\" content=\"Efficient resource allocation will help you deliver projects on time, maintain a healthy team and make sure your team&#039;s work is properly planned.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teamdeck.io\/es\/gestion-de-proyectos\/los-fallos-en-la-gestion-de-proyectos-salvan-proyectos-asignacion-de-recursos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Save Your Projects From Failure With Resource Allocation\" \/>\n<meta property=\"og:description\" content=\"Efficient resource allocation will help you deliver projects on time, maintain a healthy team and make sure your team&#039;s work is properly planned.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teamdeck.io\/es\/gestion-de-proyectos\/los-fallos-en-la-gestion-de-proyectos-salvan-proyectos-asignacion-de-recursos\/\" \/>\n<meta property=\"og:site_name\" content=\"Teamdeck\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/helloteamdeck\" \/>\n<meta property=\"article:author\" content=\"zbigniew.czarnecki\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-14T15:20:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-24T12:35:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14172642\/teamdeck_resource_allocation.jpg\" \/>\n<meta name=\"author\" content=\"Zbigniew Czarnecki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Save Your Projects From Failure With Resource Allocation\" \/>\n<meta name=\"twitter:description\" content=\"Efficient resource allocation will help you deliver projects on time, maintain a healthy team and make sure your team&#039;s work is properly planned.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14172642\/teamdeck_resource_allocation.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@z_czarnecki\" \/>\n<meta name=\"twitter:site\" content=\"@helloteamdeck\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Zbigniew Czarnecki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/\",\"url\":\"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/\",\"name\":\"Project Management Failures: Save Your Projects from Failure Thanks to...\",\"isPartOf\":{\"@id\":\"https:\/\/teamdeck.io\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/17230928\/Save-your-projects-from-failure-with-efficient-resource-allocation.jpeg\",\"datePublished\":\"2017-11-14T15:20:40+00:00\",\"dateModified\":\"2022-05-24T12:35:33+00:00\",\"author\":{\"@id\":\"https:\/\/teamdeck.io\/#\/schema\/person\/8f098b02d80e39292c6e9a03aefeb0b1\"},\"description\":\"Efficient resource allocation will help you deliver projects on time, maintain a healthy team and make sure your team's work is properly planned.\",\"breadcrumb\":{\"@id\":\"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#primaryimage\",\"url\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/17230928\/Save-your-projects-from-failure-with-efficient-resource-allocation.jpeg\",\"contentUrl\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/17230928\/Save-your-projects-from-failure-with-efficient-resource-allocation.jpeg\",\"width\":1470,\"height\":980,\"caption\":\"Project failures are caused by lack the project management software\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/teamdeck.io\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Project Management Failures: Save Your Projects from Failure Thanks to Efficient Resource Allocation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teamdeck.io\/#website\",\"url\":\"https:\/\/teamdeck.io\/\",\"name\":\"Teamdeck\",\"description\":\"resource scheduling + time tracking + leave management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teamdeck.io\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/teamdeck.io\/#\/schema\/person\/8f098b02d80e39292c6e9a03aefeb0b1\",\"name\":\"Zbigniew Czarnecki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/teamdeck.io\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/07\/17115259\/zbigniew-foto-150x150.png\",\"contentUrl\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/07\/17115259\/zbigniew-foto-150x150.png\",\"caption\":\"Zbigniew Czarnecki\"},\"sameAs\":[\"https:\/\/teamdeck.io\",\"zbigniew.czarnecki\",\"https:\/\/x.com\/z_czarnecki\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Project Management Failures: Save Your Projects from Failure Thanks to...","description":"Efficient resource allocation will help you deliver projects on time, maintain a healthy team and make sure your team's work is properly planned.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teamdeck.io\/es\/gestion-de-proyectos\/los-fallos-en-la-gestion-de-proyectos-salvan-proyectos-asignacion-de-recursos\/","og_locale":"es_ES","og_type":"article","og_title":"Save Your Projects From Failure With Resource Allocation","og_description":"Efficient resource allocation will help you deliver projects on time, maintain a healthy team and make sure your team's work is properly planned.","og_url":"https:\/\/teamdeck.io\/es\/gestion-de-proyectos\/los-fallos-en-la-gestion-de-proyectos-salvan-proyectos-asignacion-de-recursos\/","og_site_name":"Teamdeck","article_publisher":"https:\/\/www.facebook.com\/helloteamdeck","article_author":"zbigniew.czarnecki","article_published_time":"2017-11-14T15:20:40+00:00","article_modified_time":"2022-05-24T12:35:33+00:00","og_image":[{"url":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14172642\/teamdeck_resource_allocation.jpg","type":"","width":"","height":""}],"author":"Zbigniew Czarnecki","twitter_card":"summary_large_image","twitter_title":"Save Your Projects From Failure With Resource Allocation","twitter_description":"Efficient resource allocation will help you deliver projects on time, maintain a healthy team and make sure your team's work is properly planned.","twitter_image":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/14172642\/teamdeck_resource_allocation.jpg","twitter_creator":"@z_czarnecki","twitter_site":"@helloteamdeck","twitter_misc":{"Written by":"Zbigniew Czarnecki","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/","url":"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/","name":"Project Management Failures: Save Your Projects from Failure Thanks to...","isPartOf":{"@id":"https:\/\/teamdeck.io\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#primaryimage"},"image":{"@id":"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/17230928\/Save-your-projects-from-failure-with-efficient-resource-allocation.jpeg","datePublished":"2017-11-14T15:20:40+00:00","dateModified":"2022-05-24T12:35:33+00:00","author":{"@id":"https:\/\/teamdeck.io\/#\/schema\/person\/8f098b02d80e39292c6e9a03aefeb0b1"},"description":"Efficient resource allocation will help you deliver projects on time, maintain a healthy team and make sure your team's work is properly planned.","breadcrumb":{"@id":"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#primaryimage","url":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/17230928\/Save-your-projects-from-failure-with-efficient-resource-allocation.jpeg","contentUrl":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/11\/17230928\/Save-your-projects-from-failure-with-efficient-resource-allocation.jpeg","width":1470,"height":980,"caption":"Project failures are caused by lack the project management software"},{"@type":"BreadcrumbList","@id":"https:\/\/teamdeck.io\/project-management\/project-management-failures-save-projects-resource-allocation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teamdeck.io\/"},{"@type":"ListItem","position":2,"name":"Project Management Failures: Save Your Projects from Failure Thanks to Efficient Resource Allocation"}]},{"@type":"WebSite","@id":"https:\/\/teamdeck.io\/#website","url":"https:\/\/teamdeck.io\/","name":"Teamdeck","description":"resource scheduling + time tracking + leave management","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teamdeck.io\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/teamdeck.io\/#\/schema\/person\/8f098b02d80e39292c6e9a03aefeb0b1","name":"Zbigniew Czarnecki","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/teamdeck.io\/#\/schema\/person\/image\/","url":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/07\/17115259\/zbigniew-foto-150x150.png","contentUrl":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/07\/17115259\/zbigniew-foto-150x150.png","caption":"Zbigniew Czarnecki"},"sameAs":["https:\/\/teamdeck.io","zbigniew.czarnecki","https:\/\/x.com\/z_czarnecki"]}]}},"_links":{"self":[{"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/posts\/3697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/comments?post=3697"}],"version-history":[{"count":39,"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/posts\/3697\/revisions"}],"predecessor-version":[{"id":13359,"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/posts\/3697\/revisions\/13359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/media\/8730"}],"wp:attachment":[{"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/media?parent=3697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/categories?post=3697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teamdeck.io\/es\/wp-json\/wp\/v2\/tags?post=3697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}