{"id":5396,"date":"2019-10-28T14:31:42","date_gmt":"2019-10-28T12:31:42","guid":{"rendered":"https:\/\/teamdeck.io\/?p=5396"},"modified":"2022-06-17T14:15:18","modified_gmt":"2022-06-17T12:15:18","slug":"team-building-for-remote-teams","status":"publish","type":"post","link":"https:\/\/teamdeck.io\/de\/teamgluck\/teambildung-fur-remote-teams\/","title":{"rendered":"Aufbau von Remote-Teams - Lektionen von verteilten Unternehmen"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid redl-row-section padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-left vc_col-sm-12 padding-default bgv-default bgh-default halign-default\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\">Flexible Arbeitszeiten, Zeit f\u00fcr die Familie, die M\u00f6glichkeit, von \u00fcberall aus zu arbeiten: Diese Vorteile der Telearbeit wurden von den Befragten in <a href=\"https:\/\/buffer.com\/state-of-remote-work-2019\" target=\"_blank\" rel=\"noopener\">den von Buffer erstellten Jahresbericht<\/a>. Andererseits aber auch, <a href=\"https:\/\/buffer.com\/state-of-remote-work-2019\" target=\"_blank\" rel=\"noopener\">der Stand der Fernarbeit<\/a> zeigt, dass Einsamkeit nach wie vor einer der Hauptnachteile f\u00fcr Menschen ist, die in verteilten Teams arbeiten.<\/p>\n<p style=\"text-align: justify;\">Zur gleichen Zeit, <a href=\"https:\/\/knowyourteam.com\/blog\/2019\/07\/24\/how-to-build-social-connection-in-a-remote-team\/\" target=\"_blank\" rel=\"noopener\">Fernmanager geben zu<\/a> dass die \"F\u00f6rderung eines Gef\u00fchls der Verbundenheit ohne einen gemeinsamen Standort\" der schwierigste Teil ihrer Aufgabe ist. Die Bildung von Remote-Teams ist eine nat\u00fcrliche Antwort auf diese Herausforderung.<\/p>\n<p style=\"text-align: justify;\">Unternehmen entwickeln verschiedene Strategien, um die sozialen Beziehungen zwischen ihren Teammitgliedern zu f\u00f6rdern. Von Onboarding-Strategien \u00fcber den Einsatz von fernbedienungsfreundlicher Software bis hin zur Organisation von pers\u00f6nlichen Treffen bieten sie ihren Mitarbeitern zahlreiche Gelegenheiten, sich zu treffen.<\/p>\n<p style=\"text-align: justify;\">Wenn Sie selbst ein verteiltes Team leiten, sollten Sie vielleicht in die Fu\u00dfstapfen der bekanntesten Remote-First-Unternehmen treten. Lernen Sie von den Besten und werfen Sie einen Blick auf einige Beispiele f\u00fcr den Aufbau von Remote-Teams in verschiedenen Phasen der Mitarbeiterentwicklung.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Aufbau von Remote-Teams - lassen Sie sich von anderen verteilten Organisationen inspirieren<\/strong><\/h2>\n<p style=\"text-align: justify;\"><em>Hinweis: F\u00fcr diesen Artikel haben wir pro Unternehmen eine Art von Strategie f\u00fcr den Aufbau von Remote-Teams ausgew\u00e4hlt. Zugegeben, sie tun immer mehr, um ihre Mitarbeiter in Verbindung zu halten. Einige von ihnen stellen sogar Software her, die speziell f\u00fcr die effektive Zusammenarbeit per Fernzugriff entwickelt wurde.<\/em><\/p>\n<h2 style=\"text-align: justify;\"><strong>Hotjar: \"10 Dinge \u00fcber dich\"-Listen, die von neu eingestellten Remote-Mitarbeitern erstellt wurden<\/strong><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10034\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163024\/Screenshot-2022-03-28-at-16.28.22-1.png\" alt=\"\" width=\"2650\" height=\"1330\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163024\/Screenshot-2022-03-28-at-16.28.22-1.png 2650w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163024\/Screenshot-2022-03-28-at-16.28.22-1-300x151.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163024\/Screenshot-2022-03-28-at-16.28.22-1-1280x642.png 1280w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163024\/Screenshot-2022-03-28-at-16.28.22-1-768x385.png 768w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163024\/Screenshot-2022-03-28-at-16.28.22-1-1536x771.png 1536w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163024\/Screenshot-2022-03-28-at-16.28.22-1-2048x1028.png 2048w\" sizes=\"auto, (max-width: 2650px) 100vw, 2650px\" \/><\/p>\n<p style=\"text-align: justify;\">Der Aufbau eines Remote-Teams beginnt, wenn eine neue Person zum Team st\u00f6\u00dft. Die Neuank\u00f6mmlinge sollten dem Rest des Teams vorgestellt werden und dabei idealerweise auch etwas \u00fcber sich selbst erz\u00e4hlen. <a href=\"https:\/\/www.hotjar.com\/blog\/virtual-team-building-activities\/\" target=\"_blank\" rel=\"noopener\">Eine der Aufgaben, die neue Hotjar-Mitarbeiter w\u00e4hrend der Einarbeitungszeit erledigen<\/a> ist das Aufschreiben einer Reihe von Fakten \u00fcber sie.<\/p>\n<p style=\"text-align: justify;\">Dieser Prozess ist ein sofortiger Eisbrecher, weil die Leute vielleicht erfahren, dass sie eine gemeinsame Leidenschaft oder ein gemeinsames Lieblings\u00e4rgernis haben. Neue Teammitglieder werden nicht nur durch ihre Berufsbezeichnung definiert: Ihre Pers\u00f6nlichkeit kommt vom ersten Tag an zum Vorschein. Dar\u00fcber hinaus k\u00f6nnen Neulinge mehr \u00fcber ihre neuen Kollegen erfahren, indem sie ihre archivierten \"10 Fakten\"-Listen lesen.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Doist: Mentorenreisen f\u00fcr neue Teammitglieder<\/strong><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10035\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/18095015\/og-image-home.jpeg\" alt=\"Die Mission des Mentor-Unternehmens nutzt die direkte Kommunikation beim Aufbau virtueller Teams\" width=\"2400\" height=\"1256\" \/><\/p>\n<p style=\"text-align: justify;\">Die meisten Remote-Unternehmen sind sich einig, dass pers\u00f6nliche Kontakte wichtig sind. Teamtreffen und Klausurtagungen sind hier zwar unerl\u00e4sslich, haben aber ihren eigenen Zeitplan, der nicht mit der Einstellung von Mitarbeitern \u00fcbereinstimmt. Stellen Sie sich vor, Sie treten einen Monat nach einer solchen j\u00e4hrlichen Klausurtagung in ein Unternehmen ein und m\u00fcssen 11 Monate warten, bis Sie die M\u00f6glichkeit haben, weitere Kollegen pers\u00f6nlich kennenzulernen.<\/p>\n<p style=\"text-align: justify;\">Doist, ein Unternehmen, das f\u00fcr seinen Remote-First-Ansatz bekannt ist, beschloss <a href=\"https:\/\/doist.com\/blog\/remote-team-communication-tools\/\" target=\"_blank\" rel=\"noopener\">die Einf\u00fchrung von Mentorenreisen f\u00fcr ihre Angestellten<\/a>. Neue Teammitglieder k\u00f6nnen eine Woche lang pers\u00f6nlich mit ihrem Mentor zusammenarbeiten.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Puffer: Technologie zur F\u00f6rderung des Teamgeistes nutzen<\/strong><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10036\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163509\/image_processing20200409-28468-1puwchd.png\" alt=\"Virtuelle Teambuilding-Aktivit\u00e4ten im digitalen Zeitalter ber\u00fccksichtigen sinnvolle Beziehungen\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163509\/image_processing20200409-28468-1puwchd.png 1600w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163509\/image_processing20200409-28468-1puwchd-300x225.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163509\/image_processing20200409-28468-1puwchd-1280x960.png 1280w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163509\/image_processing20200409-28468-1puwchd-768x576.png 768w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163509\/image_processing20200409-28468-1puwchd-1536x1152.png 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p style=\"text-align: justify;\">Puffer ist bekannt f\u00fcr <a href=\"https:\/\/open.buffer.com\/\" target=\"_blank\" rel=\"noopener\">ihren Ansatz zum Aufbau einer Kultur des \"remote-first workplace\" mitzuteilen<\/a>. <a href=\"https:\/\/stories.buffer.com\/slack-bots-for-remote-teams-909ea7d2c2ba\" target=\"_blank\" rel=\"noopener\">In einem ihrer Blogbeitr\u00e4ge<\/a>haben sie eine Reihe von Apps aufgelistet, die ihnen helfen, soziale Verbindungen zu pflegen. F\u00fcgen Sie diese auch zu Ihrem Slack-Kanal hinzu:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Facegame, eine teambildende Aktivit\u00e4t von <a href=\"https:\/\/www.officevibe.com\/\" target=\"_blank\" rel=\"noopener\">Officevibe<\/a>. Die Pr\u00e4misse ist ganz einfach: Sie m\u00fcssen ein Foto einem Teammitglied zuordnen. Es hilft nicht nur, buchst\u00e4blich einen Namen einem Gesicht zuzuordnen, sondern ist auch eine gute Idee f\u00fcr eine erfrischende Arbeitspause.<\/li>\n<li><a href=\"https:\/\/www.bitmoji.com\/\" target=\"_blank\" rel=\"noopener\">Bitmoji<\/a>die es den Mitarbeitern erm\u00f6glicht, einzigartige Emojis auf der Grundlage ihrer eigenen Eigenschaften und Hobbys zu erstellen.<\/li>\n<li><a href=\"https:\/\/www.donut.com\/\" target=\"_blank\" rel=\"noopener\">Donut<\/a>eine App, die pers\u00f6nliche Beziehungen st\u00e4rken soll. Eine ihrer Funktionen besteht darin, Mitarbeiter, die nicht allzu oft zusammenarbeiten, zusammenzubringen, damit sie die M\u00f6glichkeit haben, miteinander zu sprechen und sich kennenzulernen.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Apps wie diese helfen Ihnen, das Zusammengeh\u00f6rigkeitsgef\u00fchl und die Kameradschaft unter Ihren Teammitgliedern zu st\u00e4rken. <a href=\"https:\/\/teamdeck.io\/de\/projektleitung\/software-und-fahigkeiten-fur-das-management-von-projektteams\/\">Fernmanagement von Projektteams<\/a> geht es nicht nur um gro\u00df angelegte Einkehrtage, sondern auch um kleinere, allt\u00e4gliche Aktivit\u00e4ten, die den Menschen das Gef\u00fchl geben, Teil von etwas Gro\u00dfem zu sein.<\/p>\n<p style=\"text-align: justify;\"><em>Lesen Sie auch: <\/em><a href=\"https:\/\/teamdeck.io\/de\/projektleitung\/slack-anwendungen-fur-projektmanager\/\" target=\"_blank\" rel=\"noopener\"><em>Produktivit\u00e4tssteigernde Slack-Apps f\u00fcr Projektmanager (fernbedienbar!)<\/em><\/a><\/p>\n<h2 style=\"text-align: justify;\"><strong>Gitlab: F\u00f6rderung der informellen Kommunikation mit Breakout Calls<\/strong><\/h2>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/about.gitlab.com\/company\/culture\/all-remote\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10037\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163733\/b96521d07ec01801331b4eec8d399c84f2131050.png\" alt=\"Teamleiter kommunizieren bei Teambuilding-Aktivit\u00e4ten aus der Ferne mit Online-Meetings\" width=\"1838\" height=\"1148\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163733\/b96521d07ec01801331b4eec8d399c84f2131050.png 1838w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163733\/b96521d07ec01801331b4eec8d399c84f2131050-300x187.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163733\/b96521d07ec01801331b4eec8d399c84f2131050-1280x799.png 1280w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163733\/b96521d07ec01801331b4eec8d399c84f2131050-768x480.png 768w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163733\/b96521d07ec01801331b4eec8d399c84f2131050-1536x959.png 1536w\" sizes=\"auto, (max-width: 1838px) 100vw, 1838px\" \/>Es gibt ein ganzes Handbuch \u00fcber die Gitlab-Kultur in der Ferne<\/a> und es ist definitiv eine interessante Lekt\u00fcre f\u00fcr Menschen, die mit virtuellen Teams arbeiten. <a href=\"https:\/\/about.gitlab.com\/company\/culture\/all-remote\/informal-communication\/\" target=\"_blank\" rel=\"noopener\">Eine ihrer Priorit\u00e4ten<\/a> ist es, eine informelle Kommunikation zu erm\u00f6glichen, die in entfernten Teams schwieriger zu erreichen ist. Ihr Ansatz besteht darin, offiziell Gelegenheiten f\u00fcr die Interaktion der Mitarbeiter zu schaffen.<\/p>\n<p style=\"text-align: justify;\">Die t\u00e4glich stattfindenden Breakout Calls sind nicht arbeitsbezogenen Themen gewidmet. Die Mitarbeiter von Gitlab werden in Gruppen eingeteilt, die <a href=\"https:\/\/about.gitlab.com\/handbook\/communication\/#breakout-call\" target=\"_blank\" rel=\"noopener\">alle zwei Monate gewechselt<\/a> je nach Anwesenheit der Gruppe (Ziel ist es, die Gruppen relativ gleichm\u00e4\u00dfig zu halten). Die Gespr\u00e4chsrunden dauern 10-15 Minuten und sind den Themen Hobbys, Kultur, Familie usw. gewidmet. Jeder Teilnehmer wird ermutigt, w\u00e4hrend eines Gespr\u00e4chs etwas mitzuteilen.<\/p>\n<p style=\"text-align: justify;\">Breakout Calls k\u00f6nnen als \"Water Cooler Chat\" dienen: Die Mitarbeiter lernen sich kennen und haben die M\u00f6glichkeit, den Kontext zu wechseln, da die Breakout Calls nach den unternehmensweiten Gespr\u00e4chen stattfinden.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Zapier: Aufbau von halbj\u00e4hrlichen Retreats f\u00fcr Remote-Teams<\/strong><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10038\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163842\/zapier_logowanie.png\" alt=\"Virtuelle Teambuilding-Aktivit\u00e4ten zielen darauf ab, hoch engagierte Teams zu bilden\" width=\"1210\" height=\"542\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163842\/zapier_logowanie.png 1210w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163842\/zapier_logowanie-300x134.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28163842\/zapier_logowanie-768x344.png 768w\" sizes=\"auto, (max-width: 1210px) 100vw, 1210px\" \/><\/p>\n<p style=\"text-align: justify;\">Menschen arbeiten bei Zapier <a href=\"https:\/\/zapier.com\/learn\/remote-work\/how-run-company-retreat-remote-team\/\" target=\"_blank\" rel=\"noopener\">sich zweimal im Jahr treffen<\/a>. Diese unternehmensweiten Klausurtagungen dauern 4-5 Tage (der letzte Tag ist fakultativ). Was den Zeitplan anbelangt, so wird zwar einige Zeit damit verbracht, arbeitsbezogene Dinge zu besprechen, aber der Schwerpunkt liegt auf teambildenden Aktivit\u00e4ten.<\/p>\n<p style=\"text-align: justify;\">Wir haben uns hier nicht ohne Grund f\u00fcr Zapier als Beispielunternehmen entschieden. Ihre Retreats zeigen, dass Teambuilding auch mit einfachen Aktivit\u00e4ten erfolgreich sein kann. Wenn Sie ein Budget (und Freiwillige) f\u00fcr einen Fallschirmsprung haben, gro\u00dfartig! Aber verschlafen Sie nicht die bescheidenen Brettspielabende oder Filmabende: Auch sie k\u00f6nnen aufregend und unvergesslich sein (\u00dcbrigens, wenn Sie sich f\u00fcr Zapiers <a href=\"https:\/\/zapier.com\/blog\/board-games\/\" target=\"_blank\" rel=\"noopener\">Lieblings-Brettspiele<\/a>hier ist eine Liste).<\/p>\n<h2 style=\"text-align: justify;\"><strong>Schlie\u00dfen: Aufzeichnung von Teamsitzungen, um sie sp\u00e4ter wieder aufzugreifen<\/strong><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10039\" src=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28164031\/Screenshot-2022-03-28-at-16.39.48.png\" alt=\"Virtuelle Teambuilding-Aktivit\u00e4ten und Team-Bonding mit Close\" width=\"2720\" height=\"1226\" srcset=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28164031\/Screenshot-2022-03-28-at-16.39.48.png 2720w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28164031\/Screenshot-2022-03-28-at-16.39.48-300x135.png 300w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28164031\/Screenshot-2022-03-28-at-16.39.48-1280x577.png 1280w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28164031\/Screenshot-2022-03-28-at-16.39.48-768x346.png 768w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28164031\/Screenshot-2022-03-28-at-16.39.48-1536x692.png 1536w, https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/28164031\/Screenshot-2022-03-28-at-16.39.48-2048x923.png 2048w\" sizes=\"auto, (max-width: 2720px) 100vw, 2720px\" \/><\/p>\n<p style=\"text-align: justify;\">Wie viele Remote-First-Unternehmen hat auch Close <a href=\"https:\/\/blog.close.com\/remote-startup-team-retreats\" target=\"_blank\" rel=\"noopener\">unternehmensweite Retreats f\u00fcr ihre Mitarbeiter zu organisieren<\/a>. Das Interessante an ihrem Ansatz ist jedoch, dass sie der Aufzeichnung des Ereignisses gro\u00dfe Aufmerksamkeit schenken. Dieser Ansatz hat zwei Vorteile:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Aufzeichnungen und Live-Streams von arbeitsbezogenen Sitzungen werden f\u00fcr diejenigen n\u00fctzlich sein, die nicht an der Klausur teilnehmen konnten. Der Rest des Teams wird die M\u00f6glichkeit haben, sich diese ebenfalls anzuschauen.<\/li>\n<li>Fotos und Videos sind eine tolle Erinnerung daran, wie viel Spa\u00df es gemacht hat, gemeinsam etwas zu unternehmen. Der Blick zur\u00fcck auf gl\u00fcckliche Erinnerungen wird den Mitarbeitern neue Energie geben.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Eine Lektion f\u00fcr Sie? Genie\u00dfen Sie den Moment w\u00e4hrend der Teambesprechung, aber stellen Sie sicher, dass auch jemand diesen Moment festh\u00e4lt.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Erfahren Sie mehr \u00fcber die Verwaltung von Remote-Teams<\/strong><\/h2>\n<p style=\"text-align: justify;\">Mit der Zunahme der Fernarbeitskr\u00e4fte auf <a href=\"https:\/\/remoters.net\/remote-work-trends-future-insights\/\" target=\"_blank\" rel=\"noopener\">3,9 Millionen Menschen allein in den USA<\/a>ist der Trend zum \"No-Office\" definitiv weiter auf dem Vormarsch. Die in diesem Artikel beschriebenen Strategien zum Aufbau von Remote-Teams werden Ihnen helfen, ein Gef\u00fchl der Kameradschaft zu entwickeln und das Engagement Ihrer Mitarbeiter zu f\u00f6rdern. Dies wird sich wiederum positiv auf die Leistung Ihres Teams auswirken. Eine Studie <a href=\"https:\/\/www.fastcompany.com\/3036935\/why-you-need-to-actually-talk-to-your-coworkers-face-to-face\" target=\"_blank\" rel=\"noopener\">zitiert von Susan Pinker in ihrem Buch, <em>Der Dorfeffekt<\/em><\/a><em>, <\/em>hat gezeigt, dass Menschen, die 15 Minuten mit sozialen Kontakten verbracht haben, ihre Arbeitsleistung um 20% gesteigert haben, was sich auch auf Ihr Unternehmen auswirkt. Es liegt auf der Hand, dass die Bildung von Remote-Teams nicht ignoriert werden kann.<\/p>\n<p style=\"text-align: justify;\">Denken Sie daran, Feedback einzuholen. Ermutigen Sie Ihre Mitarbeiter, ihre Lieblingsaktivit\u00e4ten zur Teambildung mitzuteilen und auch die, die ihnen nicht so gut gefallen haben. Sowohl positive als auch negative Bemerkungen werden Ihnen helfen, ihnen in Zukunft eine bessere Erfahrung bei der Fernarbeit zu bieten.<\/p>\n<p style=\"text-align: justify;\"><strong>F\u00fcr weitere Ressourcen \u00fcber <\/strong><a href=\"https:\/\/teamdeck.io\/de\/projektleitung\/projekte-in-virtuellen-teams-verwalten\/\" target=\"_blank\" rel=\"noopener\"><strong>Verwaltung verteilter Teams<\/strong><\/a><strong> folgen Sie unserem Blog und lesen Sie diese Artikel:<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/teamdeck.io\/de\/projektleitung\/management-der-arbeitsbelastung-des-teams\/\" target=\"_blank\" rel=\"noopener\">Verwaltung der Arbeitsbelastung des Teams<\/a> - erfahren Sie, wie Sie die Sichtbarkeit Ihrer Remote-Teammitglieder erh\u00f6hen k\u00f6nnen.<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/teamdeck.io\/de\/teamgluck\/projekttransparenz\/\" target=\"_blank\" rel=\"noopener\">Transparenz des Projekts<\/a> - Eine klare Kommunikation hilft Ihnen, Missverst\u00e4ndnisse zu vermeiden.<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/teamdeck.io\/de\/teamdeck\/mobile-zeiterfassung\/\" target=\"_blank\" rel=\"noopener\">Mobile Zeiterfassung<\/a> - Die Zeiterfassung f\u00fcr unterwegs k\u00f6nnte eine gro\u00dfartige L\u00f6sung f\u00fcr die digitalen Nomaden in Ihrem Team sein. Sie k\u00f6nnen ihre Arbeitszeit bequem kontrollieren und Sie erhalten einen umfassenden Bericht \u00fcber die Arbeitsbelastung Ihres Teams und den Fortschritt Ihrer Projekte.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section feature-row vc_custom_1574416816256 vc_row-o-equal-height vc_row-o-content-middle vc_row-flex padding-medium bgv-default bgh-default halign-center\"><\/div><div class=\"vc_row wpb_row vc_row-fluid redl-row-section vc_row-o-content-middle vc_row-flex padding-default bgv-default bgh-default halign-default\"><div class=\"wpb_column vc_column_container text-center vc_col-sm-12 padding-default bgv-default bgh-default halign-center\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 class=\"ql-align-center\" style=\"text-align: center;\"><strong>Suchen Sie eine Software f\u00fcr die effiziente Verwaltung und den Aufbau von Remote-Teams? <\/strong><\/h2>\n<h3 class=\"ql-align-center\" style=\"text-align: center;\"><strong>Einfaches Ressourcenmanagement f\u00fcr Remote-Teams mit\u00a0<a href=\"https:\/\/teamdeck.io\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ressourcenplanungs-Software<\/a>\u00a0ausgew\u00e4hlt von internationalen IT- und Werbeunternehmen<\/strong><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<a class=\"redl-btn   vc_custom_1596025898618 redl-btn-medium redl-btn-6a572fc5cc283 btn-icon-left redl-btn redl-btn-two vc_custom_1551260371526 redl-btn-medium redl-btn-5f2168a4adf5d btn-hover-one btn-icon-right signup-top\" href=\"https:\/\/app.teamdeck.io\/register\">Kostenlose 30-Tage-Testversion anfordern<\/a><div class=\"vc_empty_space\"   style=\"height: 32px\" ><span class=\"vc_empty_space_inner\"><\/span><\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"Flexible Zeiteinteilung, Zeit f\u00fcr die Familie, die M\u00f6glichkeit, von \u00fcberall aus zu arbeiten: Diese Vorteile der Fernarbeit wurden von den Befragten in dem von Buffer erstellten Jahresbericht hervorgehoben. Auf der anderen Seite aber hat der Staat...","protected":false},"author":6,"featured_media":8672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-5396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-team-happiness"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.8 (Yoast SEO v24.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Building Remote Teams: Lessons from Distributed Companies<\/title>\n<meta name=\"description\" content=\"What are the most effective remote team building strategies? Get inspiration from the best disributed companies and boost your organization&#039;s team spirit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teamdeck.io\/de\/teamgluck\/teambildung-fur-remote-teams\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Building Remote Teams - Lessons from Distributed Companies\" \/>\n<meta property=\"og:description\" content=\"What are the most effective remote team building strategies? Get inspiration from the best disributed companies and boost your organization&#039;s team spirit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teamdeck.io\/de\/teamgluck\/teambildung-fur-remote-teams\/\" \/>\n<meta property=\"og:site_name\" content=\"Teamdeck\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/helloteamdeck\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-28T12:31:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-17T12:15:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/17215628\/Team-building-for-Remote-Teams.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1470\" \/>\n\t<meta property=\"og:image:height\" content=\"980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ania Kitowska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@helloteamdeck\" \/>\n<meta name=\"twitter:site\" content=\"@helloteamdeck\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ania Kitowska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/\",\"url\":\"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/\",\"name\":\"Building Remote Teams: Lessons from Distributed Companies\",\"isPartOf\":{\"@id\":\"https:\/\/teamdeck.io\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/17215628\/Team-building-for-Remote-Teams.jpeg\",\"datePublished\":\"2019-10-28T12:31:42+00:00\",\"dateModified\":\"2022-06-17T12:15:18+00:00\",\"author\":{\"@id\":\"https:\/\/teamdeck.io\/#\/schema\/person\/38139dc474576295e51cfae1580d697e\"},\"description\":\"What are the most effective remote team building strategies? Get inspiration from the best disributed companies and boost your organization's team spirit.\",\"breadcrumb\":{\"@id\":\"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#primaryimage\",\"url\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/17215628\/Team-building-for-Remote-Teams.jpeg\",\"contentUrl\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/17215628\/Team-building-for-Remote-Teams.jpeg\",\"width\":1470,\"height\":980,\"caption\":\"Virtual team building activities\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/teamdeck.io\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Building Remote Teams &#8211; Lessons from Distributed Companies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teamdeck.io\/#website\",\"url\":\"https:\/\/teamdeck.io\/\",\"name\":\"Teamdeck\",\"description\":\"resource scheduling + time tracking + leave management\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teamdeck.io\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/teamdeck.io\/#\/schema\/person\/38139dc474576295e51cfae1580d697e\",\"name\":\"Ania Kitowska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/teamdeck.io\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/09\/25113607\/aniaprofil%C3%B3wka-150x150.jpg\",\"contentUrl\":\"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/09\/25113607\/aniaprofil%C3%B3wka-150x150.jpg\",\"caption\":\"Ania Kitowska\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Building Remote Teams: Lessons from Distributed Companies","description":"What are the most effective remote team building strategies? Get inspiration from the best disributed companies and boost your organization's team spirit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teamdeck.io\/de\/teamgluck\/teambildung-fur-remote-teams\/","og_locale":"de_DE","og_type":"article","og_title":"Building Remote Teams - Lessons from Distributed Companies","og_description":"What are the most effective remote team building strategies? Get inspiration from the best disributed companies and boost your organization's team spirit.","og_url":"https:\/\/teamdeck.io\/de\/teamgluck\/teambildung-fur-remote-teams\/","og_site_name":"Teamdeck","article_publisher":"https:\/\/www.facebook.com\/helloteamdeck","article_published_time":"2019-10-28T12:31:42+00:00","article_modified_time":"2022-06-17T12:15:18+00:00","og_image":[{"width":1470,"height":980,"url":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/17215628\/Team-building-for-Remote-Teams.jpeg","type":"image\/jpeg"}],"author":"Ania Kitowska","twitter_card":"summary_large_image","twitter_creator":"@helloteamdeck","twitter_site":"@helloteamdeck","twitter_misc":{"Written by":"Ania Kitowska","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/","url":"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/","name":"Building Remote Teams: Lessons from Distributed Companies","isPartOf":{"@id":"https:\/\/teamdeck.io\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#primaryimage"},"image":{"@id":"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/17215628\/Team-building-for-Remote-Teams.jpeg","datePublished":"2019-10-28T12:31:42+00:00","dateModified":"2022-06-17T12:15:18+00:00","author":{"@id":"https:\/\/teamdeck.io\/#\/schema\/person\/38139dc474576295e51cfae1580d697e"},"description":"What are the most effective remote team building strategies? Get inspiration from the best disributed companies and boost your organization's team spirit.","breadcrumb":{"@id":"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#primaryimage","url":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/17215628\/Team-building-for-Remote-Teams.jpeg","contentUrl":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2019\/10\/17215628\/Team-building-for-Remote-Teams.jpeg","width":1470,"height":980,"caption":"Virtual team building activities"},{"@type":"BreadcrumbList","@id":"https:\/\/teamdeck.io\/team-happiness\/team-building-for-remote-teams\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teamdeck.io\/"},{"@type":"ListItem","position":2,"name":"Building Remote Teams &#8211; Lessons from Distributed Companies"}]},{"@type":"WebSite","@id":"https:\/\/teamdeck.io\/#website","url":"https:\/\/teamdeck.io\/","name":"Teamdeck","description":"resource scheduling + time tracking + leave management","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teamdeck.io\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/teamdeck.io\/#\/schema\/person\/38139dc474576295e51cfae1580d697e","name":"Ania Kitowska","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/teamdeck.io\/#\/schema\/person\/image\/","url":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/09\/25113607\/aniaprofil%C3%B3wka-150x150.jpg","contentUrl":"https:\/\/cdn.teamdeck.io\/uploads\/website\/2017\/09\/25113607\/aniaprofil%C3%B3wka-150x150.jpg","caption":"Ania Kitowska"}}]}},"_links":{"self":[{"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/posts\/5396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/comments?post=5396"}],"version-history":[{"count":12,"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/posts\/5396\/revisions"}],"predecessor-version":[{"id":11182,"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/posts\/5396\/revisions\/11182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/media\/8672"}],"wp:attachment":[{"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/media?parent=5396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/categories?post=5396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teamdeck.io\/de\/wp-json\/wp\/v2\/tags?post=5396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}